{"id":11856,"date":"2023-01-30T14:51:12","date_gmt":"2023-01-30T13:51:12","guid":{"rendered":"https:\/\/www.sab.ch\/prestationi\/gestione-dorganizzazioni-e-di-reti-2\/smart-villages\/"},"modified":"2025-02-13T09:10:08","modified_gmt":"2025-02-13T08:10:08","slug":"smart-villages","status":"publish","type":"page","link":"https:\/\/www.sab.ch\/it\/prestationi\/gestione-dorganizzazioni-e-di-reti-2\/smart-villages\/","title":{"rendered":"Smart Villages"},"content":{"rendered":"<div  class='flex_column av-35fzsu-1c49ad9bd1d126ac20c796051aafcbfb av_two_third  avia-builder-el-0  avia-builder-el-no-sibling  first flex_column_div  '     ><section  class='av_textblock_section av-lna4p2hb-312520c7cd86fdc20cfa8e68c4c8dcd1 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2 class=\"csc-firstHeader\">Insieme per diventare un villaggio intelligente !<\/h2>\n<p>Come si pu\u00f2 utilizzare la digitalizzazione in modo intelligente nelle regioni di montagna, a beneficio delle loro popolazioni e dei loro ospiti ? Il Gruppo svizzero per le regioni di montagna (SAB), e la Segreteria di Stato dell\u2019economia (SECO), con la partecipazione di una quarantina di comuni di montagna, intendono approfondire questa questione. Nell\u2019ambito della Nuova politica regionale (NPR), lanceranno congiuntamente la misura pilota \u00ab Villaggi intelligenti \/ Regioni intelligenti \u00bb. Contattateci se volete coinvolgere il vostro comune, al fine di trarre maggiori vantaggi dalla digitalizzazione !<\/p>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-m7327kxt-536b18d83122952a5aeea6074b0aef2f\">\n#top .hr.hr-invisible.av-m7327kxt-536b18d83122952a5aeea6074b0aef2f{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-m7327kxt-536b18d83122952a5aeea6074b0aef2f hr-invisible  avia-builder-el-2  el_after_av_textblock  el_before_av_textblock '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-lna4qbl6-978efce2d57977de3aa3c33c90f73066 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h3 class=\"font-xl rs-grey-dark title\">Rapporto finale misura pilota del NPR per le regioni di montagna Smart Villages \/ Smart Regions<\/h3>\n<p>La digitalizzazione schiude nuove possibilit\u00e0 ai comuni e alle regioni, ad esempio per il rafforzamento della vita sociale e della convivenza o l\u2019applicazione di nuove forme di lavoro. Nell\u2019ambito delle misure pilota NPR per le regioni di montagna, nel 2020 la Segreteria di Stato dell\u2019economia (SECO) e il Gruppo svizzero per le regioni di montagna (SAB) hanno lanciato il programma \u00abSmart Villages \/ Smart Regions\u00bb che si \u00e8 concluso nel 2022. Sono ora disponibili il rapporto finale e un video che illustrano i risultati dei 24 comuni partecipanti.<\/p>\n<p><a href=\"https:\/\/www.sab.ch\/wp-content\/uploads\/2023\/10\/Schlussbericht-Smart-Villages-Smart-Regions-2023.pdf\">Rapporto finale\u00a0<\/a><\/p>\n<\/div><\/section><br \/>\n<div  class='avia-video av-lna4qvm9-2b821abbca6bd5b79b8af1d7b0f114f4 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/1vChhpgaZGE'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Smart Villages \/ Smart Regions (IT)\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/1vChhpgaZGE?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-lb0kojh8-f458b21e2264cc8c44ce7bbd4328b44f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2>Scambio di esperienze ERFA &#8211; Misura pilota del PNR Villaggi intelligenti \/ Regioni intelligenti<\/h2>\n<p><span style=\"font-weight: bold;\">Data: 21 novembre 2022 a Berna <\/span><\/p>\n<p>Due anni fa, il Gruppo di lavoro svizzero per le regioni di montagna (SAB) e la Segreteria di Stato per l&#8217;economia (SECO) hanno lanciato la misura pilota &#8220;Smart Villages \/ Smart Regions&#8221; per sostenere le comunit\u00e0 montane nell&#8217;introduzione di progetti orientati al futuro. Circa due dozzine di comuni hanno beneficiato di un cofinanziamento per un processo partecipativo che ha aiutato a identificare la necessit\u00e0 di azione in un comune, a sviluppare una visione, a definire le misure Smart Villages e a redigere un piano d&#8217;azione. La misura pilota si sta lentamente concludendo e l&#8217;ERFA del 21 novembre \u00e8 il momento ideale per fare il punto della situazione e scambiare esperienze tra i comuni, gli esperti che li accompagnano e i responsabili del programma.<\/p>\n<p>Ulteriori informazioni sono disponibili <a href=\"https:\/\/sab.ch\/wp-content\/uploads\/2022\/11\/de_Erfahrungsaustausch_ERFA_def.pdf\">qui<\/a><\/p>\n<h2>Comunicato stampa<\/h2>\n<ul class=\"csc-uploads csc-uploads-0\">\n<li class=\"li-odd li-first csc-uploads-element csc-uploads-element-pdf\"><a href=\"\/wp-content\/uploads\/2022\/11\/Bergdoerfer_werden_zu__Smart_Villages_.pdf\">I villaggi di montagna diventano &#8220;Smart Villages&#8221; (16.11.2021)<\/a><\/li>\n<li class=\"li-even csc-uploads-element csc-uploads-element-pdf\"><a href=\"https:\/\/www.sab.ch\/wp-content\/uploads\/2023\/02\/CS_SmartVillages_10.11.2020_it.pdf\">Villaggi intelligenti: quali politiche sono necessarie per promuovere i villaggi intelligenti? (10.11.2020)<\/a><\/li>\n<\/ul>\n<h2>Documenti (nelle lingua originale)<\/h2>\n<ul class=\"csc-uploads csc-uploads-0\">\n<li class=\"li-odd li-first csc-uploads-element csc-uploads-element-pdf\"><a href=\"https:\/\/www.sab.ch\/wp-content\/uploads\/2023\/02\/Insieme-per-diventare-un-villaggio-intelligente.pdf\">Factsheet Smart Villages<\/a><\/li>\n<li class=\"li-even csc-uploads-element csc-uploads-element-pdf\"><a href=\"https:\/\/www.sab.ch\/wp-content\/uploads\/2023\/02\/Capitolato-doneri-per-i-comuni-o-gruppi-di-comuni.pdf\">Termini di riferimento per i comuni\/gruppi<\/a><\/li>\n<li class=\"li-odd csc-uploads-element csc-uploads-element-pdf\"><a href=\"https:\/\/www.sab.ch\/wp-content\/uploads\/2023\/02\/Capitolato-doneri-per-gli-esperti-esterni.pdf\">Termini di riferimento per gli esperti esterni<\/a><\/li>\n<li class=\"li-even csc-uploads-element csc-uploads-element-pdf\"><a href=\"https:\/\/www.sab.ch\/wp-content\/uploads\/2023\/02\/itdef_NPR_Smart_villages_Liste_experts.pdf\">NRP Smart villages Consulente<\/a><\/li>\n<\/ul>\n<h2>Presentazioni Conferenza sui villaggi intelligenti 10.11.2020<\/h2>\n<ul class=\"csc-uploads csc-uploads-0\">\n<li class=\"li-odd li-first csc-uploads-element csc-uploads-element-pdf\"><a href=\"\/wp-content\/uploads\/2022\/11\/MariaLezziSAB_SmartVillagesPolicy_conferencefinal.pdf\">Maria Lezzi: Policy conference of the Smart Villages Interreg Alpine Space Project<\/a><\/li>\n<li class=\"li-even csc-uploads-element csc-uploads-element-pdf\"><a href=\"\/wp-content\/uploads\/2022\/11\/EmilijiaStojmenovaSmartVillagesPolicy_conferencefinal.pdf\">Emilija Stojmenova Duh: Smart Villages: The local heroes concept<\/a><\/li>\n<li class=\"li-odd csc-uploads-element csc-uploads-element-pdf\"><a href=\"\/wp-content\/uploads\/2022\/11\/PeterNiedererSAB_SmartVillagesPolicy_conferencefinal.pdf\">Peter Niederer: The Interreg Alpine Space Smart Villages Project<\/a><\/li>\n<li class=\"li-even csc-uploads-element csc-uploads-element-pdf\"><a href=\"\/wp-content\/uploads\/2022\/11\/ThomasEggerSmart_villages_policy_conferencefinal.pdf\">Thomas Egger: Smart Villages \u2013 a strategic priority for EUSALP<\/a><\/li>\n<\/ul>\n<h2>Links<\/h2>\n<p><a title=\"Tool\u00bb\" href=\"https:\/\/smart-villages.eu\/language\/de\/home-3\/\" target=\"Self\" rel=\"noopener\"><span lang=\"EN-US\">\u00abSmartness Self Assessment Tool\u00bb und die \u201c<\/span>Digital Exchange Platform\u00bb<\/a><\/p>\n<h2>Mappa<\/h2>\n<p>Panoramica dei comuni che partecipano alla misura pilota del PNR &#8220;Smart Villages \/ Smart Regions&#8221;:<\/p>\n<p><iframe id=\"datawrapper-chart-gYDl3\" style=\"width: 0; min-width: 100% !important; border: none;\" title=\"Smart Villages\" src=\"https:\/\/datawrapper.dwcdn.net\/gYDl3\/6\/\" height=\"460\" frameborder=\"0\" scrolling=\"no\" aria-label=\"map\"><\/iframe><script type=\"text\/javascript\">!function(){\"use strict\";window.addEventListener(\"message\",(function(e){if(void 0!==e.data[\"datawrapper-height\"]){var t=document.querySelectorAll(\"iframe\");for(var a in e.data[\"datawrapper-height\"])for(var r=0;r<t.length;r++){if(t&#091;r&#093;.contentWindow===e.source)t&#091;r&#093;.style.height=e.data&#091;\"datawrapper-height\"&#093;&#091;a&#093;+\"px\"}>)}();<\/script><span style=\"font-weight: bold;\">Contatto:<\/span><\/p>\n<p>Peter Niederer<br \/>\nVicedirettore del SAB e responsabile del dipartimento Sviluppo regionale<br \/>\nE-Mail: <a href=\"&#109;&#x61;&#105;&#x6c;&#116;&#x6f;:&#x70;e&#116;&#x65;&#114;&#x2e;&#110;&#x69;e&#x64;e&#114;&#x65;&#114;&#x40;&#115;&#x61;&#98;&#x2e;c&#x68;\">&#x70;e&#x74;&#101;&#x72;&#46;n&#x69;e&#x64;&#101;&#x72;&#101;r&#x40;&#115;&#x61;&#98;&#46;&#x63;h<\/a><\/p>\n<\/div><\/section><\/p><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":11832,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-11856","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Smart Villages - S A B<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sab.ch\/it\/prestationi\/gestione-dorganizzazioni-e-di-reti-2\/smart-villages\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Smart Villages - S A B\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sab.ch\/it\/prestationi\/gestione-dorganizzazioni-e-di-reti-2\/smart-villages\/\" \/>\n<meta property=\"og:site_name\" content=\"S A B\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-13T08:10:08+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sab.ch\\\/it\\\/prestationi\\\/gestione-dorganizzazioni-e-di-reti-2\\\/smart-villages\\\/\",\"url\":\"https:\\\/\\\/www.sab.ch\\\/it\\\/prestationi\\\/gestione-dorganizzazioni-e-di-reti-2\\\/smart-villages\\\/\",\"name\":\"Smart Villages - S A B\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sab.ch\\\/it\\\/#website\"},\"datePublished\":\"2023-01-30T13:51:12+00:00\",\"dateModified\":\"2025-02-13T08:10:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sab.ch\\\/it\\\/prestationi\\\/gestione-dorganizzazioni-e-di-reti-2\\\/smart-villages\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sab.ch\\\/it\\\/prestationi\\\/gestione-dorganizzazioni-e-di-reti-2\\\/smart-villages\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sab.ch\\\/it\\\/prestationi\\\/gestione-dorganizzazioni-e-di-reti-2\\\/smart-villages\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.sab.ch\\\/it\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servizi\",\"item\":\"https:\\\/\\\/www.sab.ch\\\/it\\\/prestationi\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gestione d\u2019organizzazioni e di reti\",\"item\":\"https:\\\/\\\/www.sab.ch\\\/it\\\/prestationi\\\/gestione-dorganizzazioni-e-di-reti-2\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Smart Villages\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sab.ch\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.sab.ch\\\/it\\\/\",\"name\":\"S A B\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sab.ch\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Smart Villages - S A B","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sab.ch\/it\/prestationi\/gestione-dorganizzazioni-e-di-reti-2\/smart-villages\/","og_locale":"it_IT","og_type":"article","og_title":"Smart Villages - S A B","og_url":"https:\/\/www.sab.ch\/it\/prestationi\/gestione-dorganizzazioni-e-di-reti-2\/smart-villages\/","og_site_name":"S A B","article_modified_time":"2025-02-13T08:10:08+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sab.ch\/it\/prestationi\/gestione-dorganizzazioni-e-di-reti-2\/smart-villages\/","url":"https:\/\/www.sab.ch\/it\/prestationi\/gestione-dorganizzazioni-e-di-reti-2\/smart-villages\/","name":"Smart Villages - S A B","isPartOf":{"@id":"https:\/\/www.sab.ch\/it\/#website"},"datePublished":"2023-01-30T13:51:12+00:00","dateModified":"2025-02-13T08:10:08+00:00","breadcrumb":{"@id":"https:\/\/www.sab.ch\/it\/prestationi\/gestione-dorganizzazioni-e-di-reti-2\/smart-villages\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sab.ch\/it\/prestationi\/gestione-dorganizzazioni-e-di-reti-2\/smart-villages\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sab.ch\/it\/prestationi\/gestione-dorganizzazioni-e-di-reti-2\/smart-villages\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.sab.ch\/it\/home\/"},{"@type":"ListItem","position":2,"name":"Servizi","item":"https:\/\/www.sab.ch\/it\/prestationi\/"},{"@type":"ListItem","position":3,"name":"Gestione d\u2019organizzazioni e di reti","item":"https:\/\/www.sab.ch\/it\/prestationi\/gestione-dorganizzazioni-e-di-reti-2\/"},{"@type":"ListItem","position":4,"name":"Smart Villages"}]},{"@type":"WebSite","@id":"https:\/\/www.sab.ch\/it\/#website","url":"https:\/\/www.sab.ch\/it\/","name":"S A B","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sab.ch\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.sab.ch\/it\/wp-json\/wp\/v2\/pages\/11856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sab.ch\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.sab.ch\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.sab.ch\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sab.ch\/it\/wp-json\/wp\/v2\/comments?post=11856"}],"version-history":[{"count":13,"href":"https:\/\/www.sab.ch\/it\/wp-json\/wp\/v2\/pages\/11856\/revisions"}],"predecessor-version":[{"id":25565,"href":"https:\/\/www.sab.ch\/it\/wp-json\/wp\/v2\/pages\/11856\/revisions\/25565"}],"up":[{"embeddable":true,"href":"https:\/\/www.sab.ch\/it\/wp-json\/wp\/v2\/pages\/11832"}],"wp:attachment":[{"href":"https:\/\/www.sab.ch\/it\/wp-json\/wp\/v2\/media?parent=11856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}